{"id":36046,"date":"2025-12-06T16:08:42","date_gmt":"2025-12-06T16:08:42","guid":{"rendered":"https:\/\/www.favjersey.com\/?post_type=product&#038;p=36046"},"modified":"2026-07-15T09:11:04","modified_gmt":"2026-07-15T09:11:04","slug":"pittsburgh-pirates-nike-ausweich-replik-trikot-schwarz-grose-2","status":"publish","type":"product","link":"https:\/\/www.favjersey.com\/de\/product\/pittsburgh-pirates-nike-alternate-replica-team-jersey-black-2\/","title":{"rendered":"Pittsburgh Pirates Nike Alternate Replica Team Jersey - Schwarz"},"content":{"rendered":"<p>Als absoluter Fan der Pittsburgh Pirates verdienst du denselben Look, den deine Lieblingsspieler auf dem Spielfeld tragen. Dieses \u201eAlternate Replica Team\u201c-Trikot von Nike bringt das offizielle Design des Teams in deine Garderobe und sorgt so an Spieltagen stets f\u00fcr einen mitrei\u00dfenden Look. Das Polyester-Material und das schicke Pittsbur<br \/>\nProdukt-ID: 3588534<br \/>\nAbgerundeter Saum<br \/>\nKurzarm<br \/>\nDurchgehende Kn\u00f6pfe vorne<br \/>\nHei\u00dfversiegelte Jock-Tags<br \/>\nHei\u00dfversiegelte Transferapplikation<br \/>\nMLB Batterman-Applikation auf der hinteren Nackenmitte<br \/>\nTipp zur Gr\u00f6\u00dfenbestimmung: Das Produkt f\u00e4llt gro\u00df aus. Wir empfehlen, eine Gr\u00f6\u00dfe kleiner zu bestellen als Sie normalerweise tragen.<br \/>\nMaterial: 100% Polyester<br \/>\nSchonend in der Maschine waschen oder chemisch reinigen. Im W\u00e4schetrockner auf niedriger Stufe trocknen, lieber h\u00e4ngend trocknen.<br \/>\nReplik<br \/>\nEingef\u00fchrt<\/p>","protected":false},"excerpt":{"rendered":"<ul>\n<li>Fan-Edition Trikot mit dem alternativen Look der Mannschaft<\/li>\n<li>Auff\u00e4llige schwarze Grundfarbe mit klassischen Team-Akzenten<\/li>\n<li>Hergestellt aus strapazierf\u00e4higem, pflegeleichtem 100%-Polyestergewebe<\/li>\n<li>Mit dem unverwechselbaren Teamnamen und den Logo-Grafiken<\/li>\n<li>Von Fans inspiriertes Design f\u00fcr Komfort und Stil im Alltag<\/li>\n<li>Gestickte Details f\u00fcr ein hochwertiges Finish<\/li>\n<li>Weltweiter Versand, schnelle Lieferung in 10 Tagen<\/li>\n<\/ul>","protected":false},"featured_media":36046,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[2171],"product_tag":[4723,2172],"class_list":{"0":"post-36046","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-pittsburgh-pirates","7":"product_tag-blank-jersey","8":"product_tag-pittsburgh-pirates","10":"first","11":"instock","12":"sale","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.7 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pittsburgh Pirates Nike Alternate Fan edition Team Jersey - Black<\/title>\n<meta name=\"description\" content=\"Shop Pittsburgh Pirates Nike Alternate Fan edition Team Jersey - Black. $23.99. Fast 10-day worldwide delivery. Order now!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.favjersey.com\/de\/produkt\/pittsburgh-pirates-nike-ausweich-replik-trikot-schwarz-grose-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pittsburgh Pirates Nike Alternate Replica Team Jersey - Black\" \/>\n<meta property=\"og:description\" content=\"Shop Pittsburgh Pirates Nike Alternate Fan edition Team Jersey - Black. $23.99. Fast 10-day worldwide delivery. Order now!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.favjersey.com\/de\/produkt\/pittsburgh-pirates-nike-ausweich-replik-trikot-schwarz-grose-2\/\" \/>\n<meta property=\"og:site_name\" content=\"FavJersey\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T09:11:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/img.favjersey.com\/jd-product-img\/mens-nike-black-pittsburgh-pirates-alternate-replica-team-jersey_pi3588000_altimages_ff_3588532-ddc9135a0abbefa1c79balt1_full.jpg_hv_2_amp_w_1200-1000x1000.jpeg?x-oss-process=image\/resize,m_fill,w_800\/format,webp\/quality,q_80\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/img.favjersey.com\/jd-product-img\/mens-nike-black-pittsburgh-pirates-alternate-replica-team-jersey_pi3588000_altimages_ff_3588532-ddc9135a0abbefa1c79balt1_full.jpg_hv_2_amp_w_1200-1000x1000.jpeg?x-oss-process=image\/resize,m_fill,w_800\/format,webp\/quality,q_80\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.favjersey.com\\\/product\\\/pittsburgh-pirates-nike-alternate-replica-team-jersey-black-2\\\/\",\"url\":\"https:\\\/\\\/www.favjersey.com\\\/product\\\/pittsburgh-pirates-nike-alternate-replica-team-jersey-black-2\\\/\",\"name\":\"Pittsburgh Pirates Nike Alternate Fan edition Team Jersey - Black\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.favjersey.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.favjersey.com\\\/product\\\/pittsburgh-pirates-nike-alternate-replica-team-jersey-black-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.favjersey.com\\\/product\\\/pittsburgh-pirates-nike-alternate-replica-team-jersey-black-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/img.favjersey.com\\\/jd-product-img\\\/mens-nike-black-pittsburgh-pirates-alternate-replica-team-jersey_pi3588000_altimages_ff_3588532-ddc9135a0abbefa1c79balt1_full.jpg_hv_2_amp_w_1200-1000x1000.jpeg\",\"datePublished\":\"2025-12-06T16:08:42+00:00\",\"dateModified\":\"2026-07-15T09:11:04+00:00\",\"description\":\"Shop Pittsburgh Pirates Nike Alternate Fan edition Team Jersey - Black. $23.99. Fast 10-day worldwide delivery. Order now!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.favjersey.com\\\/product\\\/pittsburgh-pirates-nike-alternate-replica-team-jersey-black-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.favjersey.com\\\/product\\\/pittsburgh-pirates-nike-alternate-replica-team-jersey-black-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.favjersey.com\\\/product\\\/pittsburgh-pirates-nike-alternate-replica-team-jersey-black-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/img.favjersey.com\\\/jd-product-img\\\/mens-nike-black-pittsburgh-pirates-alternate-replica-team-jersey_pi3588000_altimages_ff_3588532-ddc9135a0abbefa1c79balt1_full.jpg_hv_2_amp_w_1200-1000x1000.jpeg\",\"contentUrl\":\"https:\\\/\\\/img.favjersey.com\\\/jd-product-img\\\/mens-nike-black-pittsburgh-pirates-alternate-replica-team-jersey_pi3588000_altimages_ff_3588532-ddc9135a0abbefa1c79balt1_full.jpg_hv_2_amp_w_1200-1000x1000.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.favjersey.com\\\/product\\\/pittsburgh-pirates-nike-alternate-replica-team-jersey-black-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.favjersey.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.favjersey.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pittsburgh Pirates Nike Alternate Replica Team Jersey &#8211; Black\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.favjersey.com\\\/#website\",\"url\":\"https:\\\/\\\/www.favjersey.com\\\/\",\"name\":\"FavJersey\",\"description\":\"Buy Replica Authentic Soccer &amp; Sports Jerseys | NBA, NFL, MLB, NHL\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.favjersey.com\\\/#organization\"},\"alternateName\":\"Fav Jersey\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.favjersey.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.favjersey.com\\\/#organization\",\"name\":\"FavJersey\",\"alternateName\":\"Fav Jersey\",\"url\":\"https:\\\/\\\/www.favjersey.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.favjersey.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.favjersey.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/android-chrome-512x512-1.png\",\"contentUrl\":\"https:\\\/\\\/www.favjersey.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/android-chrome-512x512-1.png\",\"width\":250,\"height\":250,\"caption\":\"FavJersey\"},\"image\":{\"@id\":\"https:\\\/\\\/www.favjersey.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"description\":\"FavJersey is an online store selling cheap replica soccer, NBA, NFL, MLB and NHL jerseys since 2013. Fast worldwide shipping and custom name service available.\",\"email\":\"tim@favjersey.com\",\"foundingDate\":\"2013-12-12\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pittsburgh Pirates Nike Alternate Fan Edition Team-Trikot \u2013 Schwarz","description":"Pittsburgh Pirates Nike Alternate Fan Edition Team-Trikot \u2013 Schwarz kaufen. $23.99. Schnelle weltweite Lieferung innerhalb von 10 Tagen. Jetzt bestellen!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.favjersey.com\/de\/produkt\/pittsburgh-pirates-nike-ausweich-replik-trikot-schwarz-grose-2\/","og_locale":"de_DE","og_type":"article","og_title":"Pittsburgh Pirates Nike Alternate Replica Team Jersey - Black","og_description":"Shop Pittsburgh Pirates Nike Alternate Fan edition Team Jersey - Black. $23.99. Fast 10-day worldwide delivery. Order now!","og_url":"https:\/\/www.favjersey.com\/de\/produkt\/pittsburgh-pirates-nike-ausweich-replik-trikot-schwarz-grose-2\/","og_site_name":"FavJersey","article_modified_time":"2026-07-15T09:11:04+00:00","og_image":[{"url":"https:\/\/img.favjersey.com\/jd-product-img\/mens-nike-black-pittsburgh-pirates-alternate-replica-team-jersey_pi3588000_altimages_ff_3588532-ddc9135a0abbefa1c79balt1_full.jpg_hv_2_amp_w_1200-1000x1000.jpeg?x-oss-process=image\/resize,m_fill,w_800\/format,webp\/quality,q_80","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/img.favjersey.com\/jd-product-img\/mens-nike-black-pittsburgh-pirates-alternate-replica-team-jersey_pi3588000_altimages_ff_3588532-ddc9135a0abbefa1c79balt1_full.jpg_hv_2_amp_w_1200-1000x1000.jpeg?x-oss-process=image\/resize,m_fill,w_800\/format,webp\/quality,q_80","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.favjersey.com\/product\/pittsburgh-pirates-nike-alternate-replica-team-jersey-black-2\/","url":"https:\/\/www.favjersey.com\/product\/pittsburgh-pirates-nike-alternate-replica-team-jersey-black-2\/","name":"Pittsburgh Pirates Nike Alternate Fan Edition Team-Trikot \u2013 Schwarz","isPartOf":{"@id":"https:\/\/www.favjersey.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.favjersey.com\/product\/pittsburgh-pirates-nike-alternate-replica-team-jersey-black-2\/#primaryimage"},"image":{"@id":"https:\/\/www.favjersey.com\/product\/pittsburgh-pirates-nike-alternate-replica-team-jersey-black-2\/#primaryimage"},"thumbnailUrl":"https:\/\/img.favjersey.com\/jd-product-img\/mens-nike-black-pittsburgh-pirates-alternate-replica-team-jersey_pi3588000_altimages_ff_3588532-ddc9135a0abbefa1c79balt1_full.jpg_hv_2_amp_w_1200-1000x1000.jpeg","datePublished":"2025-12-06T16:08:42+00:00","dateModified":"2026-07-15T09:11:04+00:00","description":"Pittsburgh Pirates Nike Alternate Fan Edition Team-Trikot \u2013 Schwarz kaufen. $23.99. Schnelle weltweite Lieferung innerhalb von 10 Tagen. Jetzt bestellen!","breadcrumb":{"@id":"https:\/\/www.favjersey.com\/product\/pittsburgh-pirates-nike-alternate-replica-team-jersey-black-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.favjersey.com\/product\/pittsburgh-pirates-nike-alternate-replica-team-jersey-black-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.favjersey.com\/product\/pittsburgh-pirates-nike-alternate-replica-team-jersey-black-2\/#primaryimage","url":"https:\/\/img.favjersey.com\/jd-product-img\/mens-nike-black-pittsburgh-pirates-alternate-replica-team-jersey_pi3588000_altimages_ff_3588532-ddc9135a0abbefa1c79balt1_full.jpg_hv_2_amp_w_1200-1000x1000.jpeg","contentUrl":"https:\/\/img.favjersey.com\/jd-product-img\/mens-nike-black-pittsburgh-pirates-alternate-replica-team-jersey_pi3588000_altimages_ff_3588532-ddc9135a0abbefa1c79balt1_full.jpg_hv_2_amp_w_1200-1000x1000.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.favjersey.com\/product\/pittsburgh-pirates-nike-alternate-replica-team-jersey-black-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.favjersey.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.favjersey.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Pittsburgh Pirates Nike Alternate Replica Team Jersey &#8211; Black"}]},{"@type":"WebSite","@id":"https:\/\/www.favjersey.com\/#website","url":"https:\/\/www.favjersey.com\/","name":"FavJersey","description":"Kaufen Sie authentische Replika-Fu\u00dfball- und Sporttrikots | NBA, NFL, MLB, NHL","publisher":{"@id":"https:\/\/www.favjersey.com\/#organization"},"alternateName":"Fav Jersey","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.favjersey.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.favjersey.com\/#organization","name":"FavJersey","alternateName":"Fav Jersey","url":"https:\/\/www.favjersey.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.favjersey.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.favjersey.com\/wp-content\/uploads\/2025\/12\/android-chrome-512x512-1.png","contentUrl":"https:\/\/www.favjersey.com\/wp-content\/uploads\/2025\/12\/android-chrome-512x512-1.png","width":250,"height":250,"caption":"FavJersey"},"image":{"@id":"https:\/\/www.favjersey.com\/#\/schema\/logo\/image\/"},"description":"FavJersey ist ein Online-Shop, der billige Replik Fu\u00dfball, NBA, NFL, MLB und NHL Trikots seit 2013 verkauft. Schnelle weltweite Versand und benutzerdefinierte Namen Service zur Verf\u00fcgung.","email":"tim@favjersey.com","foundingDate":"2013-12-12"}]}},"_links":{"self":[{"href":"https:\/\/www.favjersey.com\/de\/wp-json\/wp\/v2\/product\/36046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.favjersey.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.favjersey.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.favjersey.com\/de\/wp-json\/wp\/v2\/comments?post=36046"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.favjersey.com\/de\/wp-json\/wp\/v2\/product\/36046"}],"wp:attachment":[{"href":"https:\/\/www.favjersey.com\/de\/wp-json\/wp\/v2\/media?parent=36046"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.favjersey.com\/de\/wp-json\/wp\/v2\/product_brand?post=36046"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.favjersey.com\/de\/wp-json\/wp\/v2\/product_cat?post=36046"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.favjersey.com\/de\/wp-json\/wp\/v2\/product_tag?post=36046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}